{"id":110,"date":"2024-02-05T12:07:13","date_gmt":"2024-02-05T15:07:13","guid":{"rendered":"https:\/\/flaviapereira.com\/?p=110"},"modified":"2026-07-28T08:44:45","modified_gmt":"2026-07-28T11:44:45","slug":"a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia","status":"publish","type":"post","link":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/","title":{"rendered":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0"},"content":{"rendered":"\n<p>Hoje te fa\u00e7o um convite para que nesse texto voc\u00ea reflita sobre a import\u00e2ncia de levar a dan\u00e7a jazz para a academia. De modo ignorante, sem a inten\u00e7\u00e3o de ser, talvez voc\u00ea pense que isso j\u00e1 exista ou aconte\u00e7a, mas no caso da dan\u00e7a jazz, s\u00f3 foram adicionados alguns elementos de bal\u00e9 cl\u00e1ssico e a ideia colonizadora de que precisava ser aprimorado.\u00a0<br>O jazz, por natureza, pode ser resumido como s\u00edncope e improvisa\u00e7\u00e3o. E \u00e9 a partir desse entendimento que se percebem as pequenas nuances nas diferentes vertentes e sobre como \u00e9 ser uma boa dan\u00e7arina (e\/ou) professora (e\/ou) de jazz.\u00a0<br>\u00a0<br>O conceito de academia, teses e afins \u00e9 branco. Por consequ\u00eancia, a ideia de que algum estudo sobre algo s\u00f3 tenha real valor e credibilidade, seja o que tenha passado pelos graus e esteja no papel; ignorando completamente toda cultura que \u00e9 passada de forma oral e tamb\u00e9m esquecendo as pessoas que ainda possuem mais dificuldade de acesso \u00e0 universidade. Uma vez que as pol\u00edticas p\u00fablicas nesse quesito sejam essenciais, embora ainda n\u00e3o sejam suficientes e eficientes.\u00a0<\/p>\n\n\n\n<p>Quando uma pessoa preta toma consci\u00eancia de sua cor e de toda cultura criada e disseminada por outras pessoas pretas, essa cultura ganha um novo peso e significado. A hist\u00f3ria, no geral, sempre foi contada por pessoas brancas em uma sociedade contempor\u00e2nea que <a href=\"https:\/\/www.bbc.com\/portuguese\/internacional-40735234\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>n\u00e3o assume seus erros<\/strong><\/a> do passado, com reflexos constantes e a estrutura ainda muito firme.&nbsp;<\/p>\n\n\n\n<p>Sendo assim, o que de fato esperar de pessoas brancas falando sobre a hist\u00f3ria de pessoas pretas? Como uma pessoa branca pode de fato entender a constru\u00e7\u00e3o social de alguma manifesta\u00e7\u00e3o art\u00edstica de resist\u00eancia racial e de orgulho, quando ela n\u00e3o sabe o que \u00e9 ser uma pessoa preta?&nbsp;<\/p>\n\n\n\n<p>L\u00f3gico, h\u00e1 diversas pessoas brancas que fazem excelentes pesquisas sobre culturas origin\u00e1rias de comunidades pretas. Mas em algum momento voc\u00ea j\u00e1 se questionou sobre o motivo de quase n\u00e3o haver pessoas negras falando sobre o mesmo assunto?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoje te fa\u00e7o um convite para que nesse texto voc\u00ea reflita sobre a import\u00e2ncia de levar a dan\u00e7a jazz para a academia. De modo ignorante, sem a inten\u00e7\u00e3o de ser, talvez voc\u00ea pense que isso j\u00e1 exista ou aconte\u00e7a, mas no caso da dan\u00e7a jazz, s\u00f3 foram adicionados alguns elementos de bal\u00e9 cl\u00e1ssico e a&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-110","post","type-post","status-publish","format-standard","hentry","category-blog"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea\" \/>\n<meta property=\"og:description\" content=\"Hoje te fa\u00e7o um convite para que nesse texto voc\u00ea reflita sobre a import\u00e2ncia de levar a dan\u00e7a jazz para a academia. De modo ignorante, sem a inten\u00e7\u00e3o de ser, talvez voc\u00ea pense que isso j\u00e1 exista ou aconte\u00e7a, mas no caso da dan\u00e7a jazz, s\u00f3 foram adicionados alguns elementos de bal\u00e9 cl\u00e1ssico e a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/\" \/>\n<meta property=\"og:site_name\" content=\"FlaP\u00ea\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-05T15:07:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-28T11:44:45+00:00\" \/>\n<meta name=\"author\" content=\"FlaP\u00ea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FlaP\u00ea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/\"},\"author\":{\"name\":\"FlaP\u00ea\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/person\\\/89c2708ac1e101a7b9c2985c7a38b4a6\"},\"headline\":\"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0\",\"datePublished\":\"2024-02-05T15:07:13+00:00\",\"dateModified\":\"2026-07-28T11:44:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/\"},\"wordCount\":363,\"publisher\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/\",\"name\":\"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#website\"},\"datePublished\":\"2024-02-05T15:07:13+00:00\",\"dateModified\":\"2026-07-28T11:44:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/02\\\/05\\\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/flaviapereira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#website\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/\",\"name\":\"FlaP\u00ea\",\"description\":\"artista da dan\u00e7a e estudiosa do jazz\",\"publisher\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flaviapereira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\",\"name\":\"FlaP\u00ea\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-icon_final-1.png\",\"contentUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-icon_final-1.png\",\"width\":189,\"height\":189,\"caption\":\"FlaP\u00ea\"},\"image\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/person\\\/89c2708ac1e101a7b9c2985c7a38b4a6\",\"name\":\"FlaP\u00ea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"contentUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"caption\":\"FlaP\u00ea\"},\"sameAs\":[\"http:\\\/\\\/flaviapereira.com\"],\"url\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/author\\\/flaviapereira-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/","og_locale":"pt_BR","og_type":"article","og_title":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea","og_description":"Hoje te fa\u00e7o um convite para que nesse texto voc\u00ea reflita sobre a import\u00e2ncia de levar a dan\u00e7a jazz para a academia. De modo ignorante, sem a inten\u00e7\u00e3o de ser, talvez voc\u00ea pense que isso j\u00e1 exista ou aconte\u00e7a, mas no caso da dan\u00e7a jazz, s\u00f3 foram adicionados alguns elementos de bal\u00e9 cl\u00e1ssico e a...","og_url":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/","og_site_name":"FlaP\u00ea","article_published_time":"2024-02-05T15:07:13+00:00","article_modified_time":"2026-07-28T11:44:45+00:00","author":"FlaP\u00ea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FlaP\u00ea","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/#article","isPartOf":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/"},"author":{"name":"FlaP\u00ea","@id":"https:\/\/flaviapereira.com\/#\/schema\/person\/89c2708ac1e101a7b9c2985c7a38b4a6"},"headline":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0","datePublished":"2024-02-05T15:07:13+00:00","dateModified":"2026-07-28T11:44:45+00:00","mainEntityOfPage":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/"},"wordCount":363,"publisher":{"@id":"https:\/\/flaviapereira.com\/#organization"},"articleSection":["Blog"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/","url":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/","name":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0 - FlaP\u00ea","isPartOf":{"@id":"https:\/\/flaviapereira.com\/#website"},"datePublished":"2024-02-05T15:07:13+00:00","dateModified":"2026-07-28T11:44:45+00:00","breadcrumb":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/02\/05\/a-importancia-de-consumir-conteudos-de-quem-se-identifica-com-a-historia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flaviapereira.com\/"},{"@type":"ListItem","position":2,"name":"A import\u00e2ncia de consumir conte\u00fados de quem se identifica com a hist\u00f3ria.\u00a0"}]},{"@type":"WebSite","@id":"https:\/\/flaviapereira.com\/#website","url":"https:\/\/flaviapereira.com\/","name":"FlaP\u00ea","description":"artista da dan\u00e7a e estudiosa do jazz","publisher":{"@id":"https:\/\/flaviapereira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flaviapereira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/flaviapereira.com\/#organization","name":"FlaP\u00ea","url":"https:\/\/flaviapereira.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flaviapereira.com\/#\/schema\/logo\/image\/","url":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2023\/12\/cropped-icon_final-1.png","contentUrl":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2023\/12\/cropped-icon_final-1.png","width":189,"height":189,"caption":"FlaP\u00ea"},"image":{"@id":"https:\/\/flaviapereira.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/flaviapereira.com\/#\/schema\/person\/89c2708ac1e101a7b9c2985c7a38b4a6","name":"FlaP\u00ea","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","url":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","contentUrl":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","caption":"FlaP\u00ea"},"sameAs":["http:\/\/flaviapereira.com"],"url":"https:\/\/flaviapereira.com\/index.php\/author\/flaviapereira-com\/"}]}},"_links":{"self":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/comments?post=110"}],"version-history":[{"count":2,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/110\/revisions"}],"predecessor-version":[{"id":501,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/110\/revisions\/501"}],"wp:attachment":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/media?parent=110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/categories?post=110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/tags?post=110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}