{"id":270,"date":"2024-10-16T22:01:35","date_gmt":"2024-10-17T01:01:35","guid":{"rendered":"https:\/\/flaviapereira.com\/?p=270"},"modified":"2026-01-01T19:12:55","modified_gmt":"2026-01-01T22:12:55","slug":"qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances","status":"publish","type":"post","link":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/","title":{"rendered":"Qual a relev\u00e2ncia da moda no jazz e nas street dances?"},"content":{"rendered":"\n<p>Nosso ponto de partida ao falar sobre street dances, \u00e9 de que estamos falando de dan\u00e7as estadunidenses oriundas das culturas negras e ind\u00edgenas; ent\u00e3o o olhar para essa relev\u00e2ncia ser\u00e1 racializado. O come\u00e7o da manifesta\u00e7\u00e3o popular miscigenada dos Estados Unidos, foi o jazz, que antes de ser o que \u00e9, foi tamb\u00e9m canto, ritmo, religi\u00e3o e poesia. \u00c9 atrav\u00e9s de m\u00e3os e vozes negras que surgem os <em>spirituals<\/em> e o ragtime.<\/p>\n\n\n\n<p>Aqui, vamos direto para o <strong>Congo Square<\/strong>, uma pra\u00e7a em New Orleans, considerada a cidade ber\u00e7o do jazz, onde pessoas negras se encontravam para reuni\u00f5es, feiras e celebra\u00e7\u00f5es de dan\u00e7as e ritmos africanos, um dos pilares no desenvolvimento do jazz.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"719\" height=\"337\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg\" alt=\"\" class=\"wp-image-271\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg 719w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square-300x141.jpg 300w\" sizes=\"auto, (max-width: 719px) 100vw, 719px\" \/><figcaption class=\"wp-element-caption\">Pintura de Ted Ellis <\/figcaption><\/figure>\n<\/div>\n\n\n<p>Essa contextualiza\u00e7\u00e3o \u00e9 porque foi a partir desses corpos que surgiram as bases para o que hoje entendemos como street dances. Sua manifesta\u00e7\u00e3o cultural foi sendo passada de maneira vernacular atrav\u00e9s das gera\u00e7\u00f5es, ou seja, tudo o que se faz hoje em rela\u00e7\u00e3o \u00e0s street dances, \u00e9 uma heran\u00e7a s\u00f3cio-cultural e ancestral do jazz e do que veio um pouco antes disso.<\/p>\n\n\n\n<p>O conjunto de circunst\u00e2ncias da \u00e9poca, fez com que o negro escravizado utilizasse a dan\u00e7a ancestral para abra\u00e7ar o banzo. Esse pode ser um dos reflexos para a busca de identidade.<\/p>\n\n\n\n<p>Essas pessoas sempre precisaram se moldar e se adaptar a uma estrutura, que al\u00e9m de n\u00e3o ter sido feita as considerando gente, tinha um sistema que animalizava mais ainda a sua imagem e se esfor\u00e7ava veemente para apagar qualquer tra\u00e7o \u00e9tinico de identifica\u00e7\u00e3o.<br>Estamos falando aqui, de um entendimento de moda eurocentrado e ocidental, num conceito que surge na Idade M\u00e9dia, quando come\u00e7a a segregar as pessoas de acordo com o tecido e a cor da roupa, aplicando num sistema de classe quem era nobre e quem n\u00e3o era.<\/p>\n\n\n\n<p>Apesar de hoje em dia as coisas n\u00e3o serem t\u00e3o extremistas assim, ainda h\u00e1 um julgamento de valor sobre algu\u00e9m a depender da roupa que estiver usando; e isso n\u00e3o era diferente no s\u00e9culo XIX, no Estados Unidos, quando pessoas negras estavam sendo alforriadas da escravid\u00e3o.<\/p>\n\n\n\n<p>Para terem o m\u00ednimo de dignidade social, essas pessoas precisaram se adapatar ao mundo em que viviam e isso inclu\u00eda as roupas que nada tinham haver com a sua hist\u00f3ria e ancestralidade. No <strong>cake walk<\/strong>, por exemplo, manifesta\u00e7\u00e3o social atrav\u00e9s da dan\u00e7a e m\u00fasica, como ferramenta de intera\u00e7\u00e3o entre brancos e negros, parte desse encontro tinha como base a necessidade de vestir suas melhores roupas, pelo conceito da branquitude sobre isso; que nada mais era do que um refor\u00e7o racista do que acontecia nos shows de menestrel, onde havia a pr\u00e1tica de <em>blackface<\/em> que se estendia para uso de roupas extravagantes e coloridas, ridicularizando a fisionomia e identidade negra.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"606\" height=\"458\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/image.png\" alt=\"\" class=\"wp-image-272\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/image.png 606w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/image-300x227.png 300w\" sizes=\"auto, (max-width: 606px) 100vw, 606px\" \/><\/figure>\n<\/div>\n\n\n<p>Anos mais tarde, na era do jazz, o vestir ainda era importante. Artistas da dan\u00e7a que no audio visual s\u00f3 apareciam representando empregos subalternos, fora desse universo, exploravam a express\u00e3o e a pr\u00f3pria identidade atrav\u00e9s das roupas que usavam. Nesse per\u00edodo do Jazz, isso se refletia tamb\u00e9m na m\u00fasica, com os <strong>hepcats<\/strong>, e se fosse uma pessoa branca interessada no jazz, um <em>hipster<\/em>.<\/p>\n\n\n\n<p>Enquanto tudo isso acontecia no universo do jazz, a m\u00e3e das street dances, a I e II Guerras Mundiais, tamb\u00e9m afetaram a ind\u00fastria da moda e a forma como a mulher branca se apresentava socialemente, que servia de padr\u00e3o.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/Hellzapoppin-1941-00-53-33.jpg\" alt=\"\" class=\"wp-image-273\" style=\"width:751px;height:auto\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/Hellzapoppin-1941-00-53-33.jpg 960w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/Hellzapoppin-1941-00-53-33-300x225.jpg 300w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/Hellzapoppin-1941-00-53-33-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"600\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/c885bd1de788212d6c1cf48bac02e721-1.jpg\" alt=\"\" class=\"wp-image-275\" style=\"width:399px;height:auto\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/c885bd1de788212d6c1cf48bac02e721-1.jpg 471w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/c885bd1de788212d6c1cf48bac02e721-1-236x300.jpg 236w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\" \/><\/figure>\n<\/div>\n\n\n<p>Em meados da d\u00e9cada de 1960 \u00e9 fundado o partido dos Panteras Negras para Auto-defesa, em respostas \u00e0 supremacia branca e a KKK. Parte do seu discurso era sobre o empoderamento negro tamb\u00e9m atrav\u00e9s da sua imagem, estimulando que os jovens afro-estadunidenses tivessem orgulho de sua fisionomia, seus cabelos e suas roupas.<\/p>\n\n\n\n<p>Poucos anos depois, em 1970, estreia o &#8220;Soul Train&#8221; um programa televisivo de entretenimento que todo s\u00e1bado pela manh\u00e3  transmitia performances musicais de artistas negros com o audit\u00f3rio mais irreverente da \u00e9poca: dezenas de jovens, tamb\u00e9m negros, que dan\u00e7avam quase o tempo inteiro. Tudo isso, durante a era <strong>black power<\/strong> e o <strong>movimento pelos direitos civis<\/strong>, protagonizados por pessoas negras.<\/p>\n\n\n\n<p>Diversos dan\u00e7arinos que participaram  do &#8220;Soul Train&#8221; se tornaram pioneiros ou refer\u00eancias para as street dances que foram sugindo nas d\u00e9cadas de 1970 e 1980. Participar do programa, era tamb\u00e9m fazer parte desse vi\u00e9s pol\u00edtico da est\u00e9tica. O que os dan\u00e7arinos vestiam era ao mesmo tempo um reflexo das tend\u00eancias de moda da \u00e9poca e um catalisador para elas.<\/p>\n\n\n\n<p>Nos anos 70, havia espa\u00e7o para v\u00e1rias coisas dentro da moda. O interessante era o simples fato de que todos se vestiam para se sentirem fabulosos. Al\u00e9m de que, pelo alcance da televis\u00e3o, todos queriam se sentir vistos (e faziam de tudo para garantir isso).<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"670\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-1024x670.jpeg\" alt=\"\" class=\"wp-image-276\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-1024x670.jpeg 1024w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-300x196.jpeg 300w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-768x503.jpeg 768w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-1536x1006.jpeg 1536w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/EmYv4oxW8AsQtTN-2048x1341.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O fato de muitas vezes as pessoas dan\u00e7arem em pares no programa, principalmente no Soul Train Line, estimulava o uso de roupas iguais, que n\u00e3o era exatamente sobre roupas andr\u00f3genas, mas que conversavam com a ideia de roupas de g\u00eanero neutro, fazendo com que a roupa fosse apenas roupa, sem distin\u00e7\u00e3o de ser feminina ou masculina.<\/p>\n\n\n\n<p>&#8220;Soul Train&#8221; conseguiu o feito de imortalizar uma era do estilo e da cultura negra. Ficou no ar por 35 anos, e obviamente as pessoas come\u00e7aram a imitar em seu dia-a-dia o que viam na televis\u00e3o: desde o soul train line, a dar mais valor, import\u00e2ncia e autoestima no que usar para ir em uma festa ou celebra\u00e7\u00e3o.<\/p>\n\n\n\n<p>Quando a gente tem o entendimento de que as street dances que vieram depois est\u00e3o ligadas \u00e0 cultura do que era feito na rua, das festas que eram produzidas e tinham um apelo visual e uma influ\u00eancia da moda de cada \u00e9poca, fica mais f\u00e1cil observar e reconhecer que a refer\u00eancia mais direta do soul train e mais indireta da era do jazz, sobre valorizar e destacar de maneira empoderada a pr\u00f3pria imagem e est\u00e9tica se estabeleceu nessas sub-culturas,<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"666\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/166061220562faee6d7cd4b_1660612205_3x2_xl-1024x666.jpg\" alt=\"\" class=\"wp-image-277\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/166061220562faee6d7cd4b_1660612205_3x2_xl-1024x666.jpg 1024w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/166061220562faee6d7cd4b_1660612205_3x2_xl-300x195.jpg 300w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/166061220562faee6d7cd4b_1660612205_3x2_xl-768x499.jpg 768w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/166061220562faee6d7cd4b_1660612205_3x2_xl.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Para finalizar e exempificar, a cultura dos bailes no Brasil, como o <strong>Chic Show<\/strong> e o movimento <strong>Black Rio<\/strong>, sentiram aqui os efeitos dos Panteras Negras e come\u00e7aram a perceber a relev\u00e2ncia da autoimagem ter personalidade. E temos tamb\u00e9m o an\u00fancio, rec\u00e9m feito, do tema do MET Gala 2025 que ser\u00e1 <em>&#8220;Black Dandyism&#8221;,<\/em> do qual recomendo fortemente a pesquisa.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"281\" src=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/1d5a84e197b11a43b0a173475f2ff68c.jpg\" alt=\"\" class=\"wp-image-278\" srcset=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/1d5a84e197b11a43b0a173475f2ff68c.jpg 450w, https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/1d5a84e197b11a43b0a173475f2ff68c-300x187.jpg 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nosso ponto de partida ao falar sobre street dances, \u00e9 de que estamos falando de dan\u00e7as estadunidenses oriundas das culturas negras e ind\u00edgenas; ent\u00e3o o olhar para essa relev\u00e2ncia ser\u00e1 racializado. O come\u00e7o da manifesta\u00e7\u00e3o popular miscigenada dos Estados Unidos, foi o jazz, que antes de ser o que \u00e9, foi tamb\u00e9m canto, ritmo, religi\u00e3o&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"categories":[1],"tags":[22,5,6,7,37,38,33],"class_list":["post-270","post","type-post","status-publish","format-standard","hentry","category-blog","tag-flape","tag-flavia-pereira","tag-jazz","tag-jazz-dance","tag-moda-no-street-dance","tag-soul-train","tag-street-dances"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea\" \/>\n<meta property=\"og:description\" content=\"Nosso ponto de partida ao falar sobre street dances, \u00e9 de que estamos falando de dan\u00e7as estadunidenses oriundas das culturas negras e ind\u00edgenas; ent\u00e3o o olhar para essa relev\u00e2ncia ser\u00e1 racializado. O come\u00e7o da manifesta\u00e7\u00e3o popular miscigenada dos Estados Unidos, foi o jazz, que antes de ser o que \u00e9, foi tamb\u00e9m canto, ritmo, religi\u00e3o...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/\" \/>\n<meta property=\"og:site_name\" content=\"FlaP\u00ea\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T01:01:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-01T22:12:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg\" \/>\n<meta name=\"author\" content=\"FlaP\u00ea\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"FlaP\u00ea\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/\"},\"author\":{\"name\":\"FlaP\u00ea\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/person\\\/89c2708ac1e101a7b9c2985c7a38b4a6\"},\"headline\":\"Qual a relev\u00e2ncia da moda no jazz e nas street dances?\",\"datePublished\":\"2024-10-17T01:01:35+00:00\",\"dateModified\":\"2026-01-01T22:12:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/\"},\"wordCount\":1119,\"publisher\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/congo-square.jpg\",\"keywords\":[\"flap\u00ea\",\"flavia pereira\",\"jazz\",\"jazz dance\",\"moda no street dance\",\"soul train\",\"street dances\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/\",\"name\":\"Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/congo-square.jpg\",\"datePublished\":\"2024-10-17T01:01:35+00:00\",\"dateModified\":\"2026-01-01T22:12:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#primaryimage\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/congo-square.jpg\",\"contentUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/congo-square.jpg\",\"width\":719,\"height\":337},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/2024\\\/10\\\/16\\\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/flaviapereira.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual a relev\u00e2ncia da moda no jazz e nas street dances?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#website\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/\",\"name\":\"FlaP\u00ea\",\"description\":\"artista da dan\u00e7a e estudiosa do jazz\",\"publisher\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/flaviapereira.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#organization\",\"name\":\"FlaP\u00ea\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-icon_final-1.png\",\"contentUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/cropped-icon_final-1.png\",\"width\":189,\"height\":189,\"caption\":\"FlaP\u00ea\"},\"image\":{\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/#\\\/schema\\\/person\\\/89c2708ac1e101a7b9c2985c7a38b4a6\",\"name\":\"FlaP\u00ea\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"url\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"contentUrl\":\"https:\\\/\\\/flaviapereira.com\\\/wp-content\\\/litespeed\\\/avatar\\\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888\",\"caption\":\"FlaP\u00ea\"},\"sameAs\":[\"http:\\\/\\\/flaviapereira.com\"],\"url\":\"https:\\\/\\\/flaviapereira.com\\\/index.php\\\/author\\\/flaviapereira-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea","og_description":"Nosso ponto de partida ao falar sobre street dances, \u00e9 de que estamos falando de dan\u00e7as estadunidenses oriundas das culturas negras e ind\u00edgenas; ent\u00e3o o olhar para essa relev\u00e2ncia ser\u00e1 racializado. O come\u00e7o da manifesta\u00e7\u00e3o popular miscigenada dos Estados Unidos, foi o jazz, que antes de ser o que \u00e9, foi tamb\u00e9m canto, ritmo, religi\u00e3o...","og_url":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/","og_site_name":"FlaP\u00ea","article_published_time":"2024-10-17T01:01:35+00:00","article_modified_time":"2026-01-01T22:12:55+00:00","og_image":[{"url":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg","type":"","width":"","height":""}],"author":"FlaP\u00ea","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"FlaP\u00ea","Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#article","isPartOf":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/"},"author":{"name":"FlaP\u00ea","@id":"https:\/\/flaviapereira.com\/#\/schema\/person\/89c2708ac1e101a7b9c2985c7a38b4a6"},"headline":"Qual a relev\u00e2ncia da moda no jazz e nas street dances?","datePublished":"2024-10-17T01:01:35+00:00","dateModified":"2026-01-01T22:12:55+00:00","mainEntityOfPage":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/"},"wordCount":1119,"publisher":{"@id":"https:\/\/flaviapereira.com\/#organization"},"image":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#primaryimage"},"thumbnailUrl":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg","keywords":["flap\u00ea","flavia pereira","jazz","jazz dance","moda no street dance","soul train","street dances"],"articleSection":["Blog"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/","url":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/","name":"Qual a relev\u00e2ncia da moda no jazz e nas street dances? - FlaP\u00ea","isPartOf":{"@id":"https:\/\/flaviapereira.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#primaryimage"},"image":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#primaryimage"},"thumbnailUrl":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg","datePublished":"2024-10-17T01:01:35+00:00","dateModified":"2026-01-01T22:12:55+00:00","breadcrumb":{"@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#primaryimage","url":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg","contentUrl":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2024\/10\/congo-square.jpg","width":719,"height":337},{"@type":"BreadcrumbList","@id":"https:\/\/flaviapereira.com\/index.php\/2024\/10\/16\/qual-a-relevancia-da-moda-no-jazz-e-nas-street-dances\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/flaviapereira.com\/"},{"@type":"ListItem","position":2,"name":"Qual a relev\u00e2ncia da moda no jazz e nas street dances?"}]},{"@type":"WebSite","@id":"https:\/\/flaviapereira.com\/#website","url":"https:\/\/flaviapereira.com\/","name":"FlaP\u00ea","description":"artista da dan\u00e7a e estudiosa do jazz","publisher":{"@id":"https:\/\/flaviapereira.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/flaviapereira.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/flaviapereira.com\/#organization","name":"FlaP\u00ea","url":"https:\/\/flaviapereira.com\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flaviapereira.com\/#\/schema\/logo\/image\/","url":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2023\/12\/cropped-icon_final-1.png","contentUrl":"https:\/\/flaviapereira.com\/wp-content\/uploads\/2023\/12\/cropped-icon_final-1.png","width":189,"height":189,"caption":"FlaP\u00ea"},"image":{"@id":"https:\/\/flaviapereira.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/flaviapereira.com\/#\/schema\/person\/89c2708ac1e101a7b9c2985c7a38b4a6","name":"FlaP\u00ea","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","url":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","contentUrl":"https:\/\/flaviapereira.com\/wp-content\/litespeed\/avatar\/01083e04261ebb90710d86f186a988fb.jpg?ver=1787789888","caption":"FlaP\u00ea"},"sameAs":["http:\/\/flaviapereira.com"],"url":"https:\/\/flaviapereira.com\/index.php\/author\/flaviapereira-com\/"}]}},"_links":{"self":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/comments?post=270"}],"version-history":[{"count":1,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/270\/revisions"}],"predecessor-version":[{"id":279,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/posts\/270\/revisions\/279"}],"wp:attachment":[{"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/media?parent=270"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/categories?post=270"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/flaviapereira.com\/index.php\/wp-json\/wp\/v2\/tags?post=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}